{"id":101600,"date":"2015-05-04T10:24:00","date_gmt":"2015-05-04T13:24:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portarias\/progepe-2015-11253\/"},"modified":"2023-08-03T12:01:43","modified_gmt":"2023-08-03T15:01:43","slug":"progepe-2015-11253","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/progepe-2015-11253\/","title":{"rendered":"PORTARIA N\u00ba 11253\/PROGEPE, DE 04 DE MAIO DE 2015"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Pr\u00f3-Reitora de Gest\u00e3o de Pessoas da Universidade Federal do Paran\u00e1, no uso de suas atribui\u00e7\u00f5es, tendo em vista a compet\u00eancia que lhe \u00e9 conferida pela Portaria n\u00ba 2.590, de 26 de setembro de 1997, considerando o que consta na Resolu\u00e7\u00e3o n\u00ba 07\/2012-CEPE alterada pela Resolu\u00e7\u00e3o n\u00ba 61\/2012-CEPE, e ainda o que consta no processo n\u00ba 055418\/2014-90,<\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>RESOLVE:<\/strong><\/p>\n\n\n<p class=\"wp-block-paragraph\">I. Conceder progress\u00e3o funcional \u00e0 servidora ANA LUISA FAYET SALLAS \u2013 105627, lotada no Departamento de Ci\u00eancias Pol\u00edticas e Sociologia do Setor de Ci\u00eancias Humanas, do n\u00edvel 7-03 para o n\u00edvel 7-04 da classe D \u2013 Associado, conforme parecer da CPPD na avalia\u00e7\u00e3o de desempenho, a partir de 23 de janeiro de 2015.<\/p><p class=\"wp-block-paragraph\"> II. A progress\u00e3o subsequente ser\u00e1 a partir de 23 de janeiro de 2017.<\/p><p class=\"wp-block-paragraph\"><\/p>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-b1849663 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/sites\/3\/pcp\/PROGEPE\/2015\/11253PR.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I. Conceder progress\u00e3o funcional \u00e0 servidora ANA LUISA FAYET SALLAS \u2013 105627, lotada no Departamento de Ci\u00eancias Pol\u00edticas e Sociologia do Setor de Ci\u00eancias Humanas, do n\u00edvel 7-03 para o n\u00edvel 7-04 da classe D \u2013 Associado, conforme parecer da CPPD na avalia\u00e7\u00e3o de desempenho, a partir de 23 de janeiro de 2015. II. A progress\u00e3o subsequente ser\u00e1 a partir de 23 de janeiro de 2017.  {&#8220;height&#8221;:&#8221;15px&#8221;} <\/p>\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"> <!-- \/wp:spacer  {\"layout\":{\"type\":\"flex\",\"justifyContent\":\"right\"}} \n\n<div class=\"wp-block-buttons\"><!-- wp:button {\"style\":{\"border\":{\"radius\":\"0px\"}},\"className\":\"is-style-outline\",\"fontSize\":\"small\"} \n\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/pcp\/PROGEPE\/2015\/11253PR.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><!-- \/wp:button <!-\n<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"wp-custom-template-emissao-entre-01-05-2004-ate-30-06-2017","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[116],"tags":[143],"class_list":["post-101600","post","type-post","status-publish","format-standard","hentry","category-progepe","tag-progressao-promocao","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/101600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=101600"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/101600\/revisions"}],"predecessor-version":[{"id":122855,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/101600\/revisions\/122855"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=101600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=101600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=101600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}