{"id":103950,"date":"2014-01-17T10:07:00","date_gmt":"2014-01-17T12:07:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portarias\/progepe-2014-05314\/"},"modified":"2023-08-03T11:51:37","modified_gmt":"2023-08-03T14:51:37","slug":"progepe-2014-05314","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/progepe-2014-05314\/","title":{"rendered":"PORTARIA N\u00ba 05314\/PROGEPE, DE 17 DE JANEIRO DE 2014"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Pr\u00f3-Reitor de Gest\u00e3o de Pessoas da Universidade Federal do Paran\u00e1 em exerc\u00edcio, no uso de suas atribui\u00e7\u00f5es, tendo em vista a compet\u00eancia que lhe \u00e9 conferida pela Portaria n\u00ba 2.590, de 26 de setembro de 1997 e considerando o que consta no processo n\u00ba 054238\/2013-18,<\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>RESOLVE:<\/strong><\/p>\n\n\n<p class=\"wp-block-paragraph\">Autorizar o afastamento integral do servidor RODRIGO ROSI MENGARELLI &#8211; 200771, ocupante do cargo de Professor, classe Assistente, lotado no Setor Litoral, com a finalidade de participar do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Educa\u00e7\u00e3o: Curr\u00edculo, em n\u00edvel de Doutorado, da Faculdade de Educa\u00e7\u00e3o na Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo, no per\u00edodo de 04 de mar\u00e7o de 2014 a 03 de mar\u00e7o de 2016, com \u00f4nus limitado para a UFPR.<\/p><p class=\"wp-block-paragraph\"><\/p>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-b1849663 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/sites\/3\/pcp\/PROGEPE\/2014\/5314PR.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Autorizar o afastamento integral do servidor RODRIGO ROSI MENGARELLI &#8211; 200771, ocupante do cargo de Professor, classe Assistente, lotado no Setor Litoral, com a finalidade de participar do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Educa\u00e7\u00e3o: Curr\u00edculo, em n\u00edvel de Doutorado, da Faculdade de Educa\u00e7\u00e3o na Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo, no per\u00edodo de 04 de mar\u00e7o de 2014 a 03 de mar\u00e7o de 2016, com \u00f4nus limitado para a UFPR.  {&#8220;height&#8221;:&#8221;15px&#8221;} <\/p>\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"> <!-- \/wp:spacer  {\"layout\":{\"type\":\"flex\",\"justifyContent\":\"right\"}} \n\n<div class=\"wp-block-buttons\"><!-- wp:button {\"style\":{\"border\":{\"radius\":\"0px\"}},\"className\":\"is-style-outline\",\"fontSize\":\"small\"} \n\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/pcp\/PROGEPE\/2014\/5314PR.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse\n<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"wp-custom-template-emissao-entre-01-05-2004-ate-30-06-2017","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":2,"footnotes":""},"categories":[116],"tags":[123],"class_list":["post-103950","post","type-post","status-publish","format-standard","hentry","category-progepe","tag-afastamento-licenca","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/103950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=103950"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/103950\/revisions"}],"predecessor-version":[{"id":147905,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/103950\/revisions\/147905"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=103950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=103950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=103950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}