{"id":110200,"date":"2013-04-25T10:18:00","date_gmt":"2013-04-25T13:18:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portarias\/progepe-2013-01499\/"},"modified":"2023-08-03T11:45:14","modified_gmt":"2023-08-03T14:45:14","slug":"progepe-2013-01499","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/progepe-2013-01499\/","title":{"rendered":"PORTARIA N\u00ba 01499\/PROGEPE, DE 25 DE ABRIL DE 2013"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Pr\u00f3-Reitor de Gest\u00e3o de Pessoas da Universidade Federal do Paran\u00e1, no uso de suas atribui\u00e7\u00f5es, tendo em vista a compet\u00eancia que lhe \u00e9 conferida pela Portaria n\u00ba 2.590, de 26 de setembro de 1997 e considerando o que consta no processo n\u00ba 049201\/2012-89,<\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>RESOLVE:<\/strong><\/p>\n\n\n<p class=\"wp-block-paragraph\">Aposentar, nos termos do Art. 40, \u00a71\u00ba, inciso I, \u00a718 da Constitui\u00e7\u00e3o Federal c\/c Art. 6\u00ba A da Emenda Constitucional n\u00ba 41, de 31.12.2003, inclu\u00eddo pela Emenda Constitucional n\u00ba 70 de 30.03.2012, o servidor ELOIR RODRIGUES \u2013 134180, lotado na Dire\u00e7\u00e3o da Assist\u00eancia do Hospital de Clinicas, ocupante do cargo de Auxiliar de Enfermagem, n\u00edvel de classifica\u00e7\u00e3o C, n\u00edvel de capacita\u00e7\u00e3o IV, padr\u00e3o de vencimento 11, no regime de 40 (quarenta) horas semanais, com o vencimento do mencionado cargo a raz\u00e3o de 35\/35 (trinta e cinco, trinta e cinco avos), mais a gratifica\u00e7\u00e3o adicional por tempo de servi\u00e7o, prevista no Art. 67 da Lei n\u00ba 8.112\/90, no \u00edndice de 4 (quatro) por cento.<\/p><p class=\"wp-block-paragraph\"><\/p>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-b1849663 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/sites\/3\/pcp\/PROGEPE\/2013\/1499PR.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aposentar, nos termos do Art. 40, \u00a71\u00ba, inciso I, \u00a718 da Constitui\u00e7\u00e3o Federal c\/c Art. 6\u00ba A da Emenda Constitucional n\u00ba 41, de 31.12.2003, inclu\u00eddo pela Emenda Constitucional n\u00ba 70 de 30.03.2012, o servidor ELOIR RODRIGUES \u2013 134180, lotado na Dire\u00e7\u00e3o da Assist\u00eancia do Hospital de Clinicas, ocupante do cargo de Auxiliar de Enfermagem, n\u00edvel de classifica\u00e7\u00e3o C, n\u00edvel de capacita\u00e7\u00e3o IV, padr\u00e3o de vencimento 11, no regime de 40 (quarenta) horas semanais, com o vencimento do mencionado cargo a raz\u00e3o de 35\/35 (trinta e cinco, trinta e cinco avos), mais a gratifica\u00e7\u00e3o adicional por tempo de servi\u00e7o,<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"wp-custom-template-emissao-entre-01-05-2004-ate-30-06-2017","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[116],"tags":[125],"class_list":["post-110200","post","type-post","status-publish","format-standard","hentry","category-progepe","tag-aposentadoria","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/110200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=110200"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/110200\/revisions"}],"predecessor-version":[{"id":153803,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/110200\/revisions\/153803"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=110200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=110200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=110200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}