{"id":158779,"date":"2012-07-12T10:09:00","date_gmt":"2012-07-12T13:09:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portarias\/progepe-2012-15391\/"},"modified":"2023-08-03T11:38:39","modified_gmt":"2023-08-03T14:38:39","slug":"progepe-2012-15391","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/progepe-2012-15391\/","title":{"rendered":"PORTARIA N\u00ba 15391\/PROGEPE, DE 12 DE JULHO DE 2012"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Pr\u00f3-Reitor de Gest\u00e3o de Pessoas da Universidade Federal do Paran\u00e1 em exerc\u00edcio, no uso de suas atribui\u00e7\u00f5es, tendo em vista a compet\u00eancia que lhe \u00e9 conferida pela Portaria n\u00ba 2.590, de 26 de setembro de 1997 e o contido no processo n\u00ba 027566\/2012-52,<\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>RESOLVE:<\/strong><\/p>\n\n\n<p class=\"wp-block-paragraph\">Prorrogar, conforme o disposto no Art. 2\u00ba, \u00a7\u00a7 1\u00ba e 2\u00ba, do Decreto n\u00ba 6.690\/2008, a licen\u00e7a maternidade da servidora FERNANDA EMANOELA NOGUEIRA &#8211; 201196, ocupante do cargo de Bibliotec\u00e1rio &#8211; Documentalista, lotada na Biblioteca de Ci\u00eancias Humanas e Educa\u00e7\u00e3o do Sistema de Bibliotecas, no per\u00edodo de 16 de outubro de 2012 a 14 de dezembro de 2012.<\/p><p class=\"wp-block-paragraph\"><\/p>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-b1849663 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/sites\/3\/pcp\/PROGEPE\/2012\/15391PR.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prorrogar, conforme o disposto no Art. 2\u00ba, \u00a7\u00a7 1\u00ba e 2\u00ba, do Decreto n\u00ba 6.690\/2008, a licen\u00e7a maternidade da servidora FERNANDA EMANOELA NOGUEIRA &#8211; 201196, ocupante do cargo de Bibliotec\u00e1rio &#8211; Documentalista, lotada na Biblioteca de Ci\u00eancias Humanas e Educa\u00e7\u00e3o do Sistema de Bibliotecas, no per\u00edodo de 16 de outubro de 2012 a 14 de dezembro de 2012.  {&#8220;height&#8221;:&#8221;15px&#8221;} <\/p>\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"> <!-- \/wp:spacer  {\"layout\":{\"type\":\"flex\",\"justifyContent\":\"right\"}} \n\n<div class=\"wp-block-buttons\"><!-- wp:button {\"style\":{\"border\":{\"radius\":\"0px\"}},\"className\":\"is-style-outline\",\"fontSize\":\"small\"} \n\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/pcp\/PROGEPE\/2012\/15391PR.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><!-- \/wp:button <!-- \/wp:buttons\n<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"wp-custom-template-emissao-entre-01-05-2004-ate-30-06-2017","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[116],"tags":[123],"class_list":["post-158779","post","type-post","status-publish","format-standard","hentry","category-progepe","tag-afastamento-licenca","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/158779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=158779"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/158779\/revisions"}],"predecessor-version":[{"id":198147,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/158779\/revisions\/198147"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=158779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=158779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=158779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}