{"id":164283,"date":"2011-07-13T05:01:00","date_gmt":"2011-07-13T08:01:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portarias\/rt-2011-01620\/"},"modified":"2023-08-03T13:05:18","modified_gmt":"2023-08-03T16:05:18","slug":"rt-2011-01620","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/rt-2011-01620\/","title":{"rendered":"PORTARIA N\u00ba 01620\/REITORIA, DE 13 DE JULHO DE 2011"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Vice-Reitor da Universidade Federal do Paran\u00e1, no exerc\u00edcio do cargo de Reitor, no uso de suas atribui\u00e7\u00f5es considerando o que consta no artigo 9\u00ba, inciso II da Lei n\u00ba 8.112\/90 e tendo em vista o que consta no processo n\u00ba 088115\/2011-19,<\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>RESOLVE:<\/strong><\/p>\n\n\n<p class=\"wp-block-paragraph\">I. Designar, no per\u00edodo de 01 de agosto de 2011 a 31 de julho de 2012, LUIZ CARLOS DA SILVA \u2013 201320, CPF n\u00ba \u275a\u275a\u275a.\u275a\u275a\u275a.\u275a\u275a\u275a-\u275a\u275a, para exercer o cargo de confian\u00e7a de Assessor de Desenvolvimento de Projetos do REUNI, CD-03, do Gabinete do Reitor, autorizado pela Portaria do Minist\u00e9rio da Educa\u00e7\u00e3o n\u00ba 1.109, de 04 de setembro de 2008, publicada no DOU de 05.09.2008.<\/p><p class=\"wp-block-paragraph\"> II. O citado servidor cumprir\u00e1, obrigatoriamente, o regime de trabalho de tempo integral, de acordo com o disposto no \u00a7 5\u00ba, artigo 1\u00ba da Lei n\u00ba 8.168\/91.<\/p><p class=\"wp-block-paragraph\"><\/p>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-b1849663 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/sites\/3\/pcp\/RT\/2011\/1620R.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I. Designar, no per\u00edodo de 01 de agosto de 2011 a 31 de julho de 2012, LUIZ CARLOS DA SILVA \u2013 201320, CPF n\u00ba \u275a\u275a\u275a.\u275a\u275a\u275a.\u275a\u275a\u275a-\u275a\u275a, para exercer o cargo de confian\u00e7a de Assessor de Desenvolvimento de Projetos do REUNI, CD-03, do Gabinete do Reitor, autorizado pela Portaria do Minist\u00e9rio da Educa\u00e7\u00e3o n\u00ba 1.109, de 04 de setembro de 2008, publicada no DOU de 05.09.2008. II. O citado servidor cumprir\u00e1, obrigatoriamente, o regime de trabalho de tempo integral, de acordo com o disposto no \u00a7 5\u00ba, artigo 1\u00ba da Lei n\u00ba 8.168\/91.  {&#8220;height&#8221;:&#8221;15px&#8221;} <\/p>\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"> <!--\n<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"wp-custom-template-emissao-entre-01-05-2004-ate-30-06-2017","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[117],"tags":[120],"class_list":["post-164283","post","type-post","status-publish","format-standard","hentry","category-rt","tag-funcao","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/164283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=164283"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/164283\/revisions"}],"predecessor-version":[{"id":203634,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/164283\/revisions\/203634"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=164283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=164283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=164283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}