{"id":189778,"date":"2006-02-21T10:04:00","date_gmt":"2006-02-21T13:04:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portarias\/prhae-2006-09214\/"},"modified":"2023-08-03T11:03:39","modified_gmt":"2023-08-03T14:03:39","slug":"prhae-2006-09214","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/prhae-2006-09214\/","title":{"rendered":"PORTARIA N\u00ba 09214\/PRHAE, DE 21 DE FEVEREIRO DE 2006"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Pr\u00f3-Reitora de Recursos Humanos e Assuntos Estudantis da Universidade Federal do Paran\u00e1, em exerc\u00edcio, no uso de suas atribui\u00e7\u00f5es, tendo em vista a compet\u00eancia que lhe \u00e9 conferida pela Portaria n\u00ba 2.590, de 26 de setembro de 1997 e considerando o que consta no processo n\u00ba 63130\/05-36,<\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>RESOLVE:<\/strong><\/p>\n\n\n<p class=\"wp-block-paragraph\">Conceder Aposentadoria Volunt\u00e1ria Integral por Tempo de Contribui\u00e7\u00e3o em Magist\u00e9rio, nos termos do Art. 3\u00ba da Emenda Constitucional n\u00ba 41 de 31.12.03, a FERNANDA RITA AGUIAR ZAMBON \u2013 065986, lotada no Departamento de Fitotecnia e Fitossanitarismo do Setor de Ci\u00eancias Agr\u00e1rias, ocupante da categoria funcional de Magist\u00e9rio Superior, classe de Professor Adjunto, n\u00edvel IV, com Mestrado, no regime de 40 (quarenta) horas semanais, com Dedica\u00e7\u00e3o Exclusiva, com o vencimento do mencionado cargo, mais a Gratifica\u00e7\u00e3o de Atividade, institu\u00edda pela Lei Delegada n\u00ba 13\/92, mais a Gratifica\u00e7\u00e3o Adicional por Tempo de Servi\u00e7o, prevista no Art. 67 da Lei n\u00ba 8.112\/90, no \u00edndice de 21 (vinte e um por cento), calculadas sobre o vencimento b\u00e1sico, mais a Gratifica\u00e7\u00e3o de Est\u00edmulo a Doc\u00eancia institu\u00edda pela Lei n\u00ba 9.678\/98, alterada pela MP n\u00ba 208\/04, mais o percentual de 3,17 decorrente da Senten\u00e7a Judicial proferida em A\u00e7\u00e3o Ordin\u00e1ria n\u00ba 99.000.5007-0 da 2\u00aa Vara Federal &#8211; PR, mais a Vantagem Pessoal do art. 62 da Lei n\u00ba 8.112\/90, origin\u00e1ria da incorpora\u00e7\u00e3o nos termos do art. 3\u00ba a 11\u00ba da Lei n\u00ba 8.911\/94, Lei n\u00ba 9.527\/97 e Lei n\u00ba 9.624\/98, correspondente as fra\u00e7\u00f5es de d\u00e9cimos equivalentes a 02\/10 (dois d\u00e9cimos) da FG-01, mais a Vantagem Pecuni\u00e1ria Individual, Lei n\u00ba 10.698\/03.<\/p><p class=\"wp-block-paragraph\"><\/p>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-b1849663 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/sites\/3\/pcp\/PRHAE\/2006\/9214PR.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conceder Aposentadoria Volunt\u00e1ria Integral por Tempo de Contribui\u00e7\u00e3o em Magist\u00e9rio, nos termos do Art. 3\u00ba da Emenda Constitucional n\u00ba 41 de 31.12.03, a FERNANDA RITA AGUIAR ZAMBON \u2013 065986, lotada no Departamento de Fitotecnia e Fitossanitarismo do Setor de Ci\u00eancias Agr\u00e1rias, ocupante da categoria funcional de Magist\u00e9rio Superior, classe de Professor Adjunto, n\u00edvel IV, com Mestrado, no regime de 40 (quarenta) horas semanais, com Dedica\u00e7\u00e3o Exclusiva, com o vencimento do mencionado cargo, mais a Gratifica\u00e7\u00e3o de Atividade, institu\u00edda pela Lei Delegada n\u00ba 13\/92, mais a Gratifica\u00e7\u00e3o Adicional por Tempo de Servi\u00e7o, prevista no Art. 67 da Lei n\u00ba<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"wp-custom-template-emissao-entre-01-05-2004-ate-30-06-2017","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[232],"tags":[],"class_list":["post-189778","post","type-post","status-publish","format-standard","hentry","category-prhae","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/189778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=189778"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/189778\/revisions"}],"predecessor-version":[{"id":227252,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/189778\/revisions\/227252"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=189778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=189778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=189778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}