{"id":189782,"date":"2006-02-21T10:08:00","date_gmt":"2006-02-21T13:08:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portarias\/prhae-2006-09218\/"},"modified":"2023-08-03T11:03:40","modified_gmt":"2023-08-03T14:03:40","slug":"prhae-2006-09218","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/prhae-2006-09218\/","title":{"rendered":"PORTARIA N\u00ba 09218\/PRHAE, DE 21 DE FEVEREIRO DE 2006"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Pr\u00f3-Reitora de Recursos Humanos e Assuntos Estudantis da Universidade Federal do Paran\u00e1, em exerc\u00edcio, no uso de suas atribui\u00e7\u00f5es, tendo em vista a compet\u00eancia que lhe \u00e9 conferida pela Portaria n\u00ba 2.590, de 26 de setembro de 1997 e considerando o que consta no processo n\u00ba 46074\/05-11,<\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>RESOLVE:<\/strong><\/p>\n\n\n<p class=\"wp-block-paragraph\">Alterar a Portaria n\u00ba 3378\/Reitor de 11 de junho de 1985, publicada no DOU de 02.07.1985, Se\u00e7\u00e3o II, p\u00e1g. 3108, altera pela Portaria n\u00ba 2153\/PRHAE de 03 de fevereiro de 1999, publicada em DOU de 08.02.1999, para declarar, que no per\u00edodo de 19.04.1991 a 29.07.1998, a aposentadoria de ORLANDO SILVEIRA PEREIRA &#8211; 002925, foi percebida com a vantagem do artigo 192, inciso II da Lei n\u00ba 8.112\/90, em substitui\u00e7\u00e3o \u00e0 vantagem do artigo 184, inciso II, da lei n\u00ba 1711\/52, tendo em vista extens\u00e3o administrativa do contido no Parecer n\u00ba 3007\/93 &#8211; CPJ.<\/p><p class=\"wp-block-paragraph\"><\/p>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-b1849663 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/sites\/3\/pcp\/PRHAE\/2006\/9218PR.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alterar a Portaria n\u00ba 3378\/Reitor de 11 de junho de 1985, publicada no DOU de 02.07.1985, Se\u00e7\u00e3o II, p\u00e1g. 3108, altera pela Portaria n\u00ba 2153\/PRHAE de 03 de fevereiro de 1999, publicada em DOU de 08.02.1999, para declarar, que no per\u00edodo de 19.04.1991 a 29.07.1998, a aposentadoria de ORLANDO SILVEIRA PEREIRA &#8211; 002925, foi percebida com a vantagem do artigo 192, inciso II da Lei n\u00ba 8.112\/90, em substitui\u00e7\u00e3o \u00e0 vantagem do artigo 184, inciso II, da lei n\u00ba 1711\/52, tendo em vista extens\u00e3o administrativa do contido no Parecer n\u00ba 3007\/93 &#8211; CPJ.  {&#8220;height&#8221;:&#8221;15px&#8221;} <\/p>\n<div style=\"height:15px\" aria-hidden=\"true\" \n\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"wp-custom-template-emissao-entre-01-05-2004-ate-30-06-2017","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[232],"tags":[],"class_list":["post-189782","post","type-post","status-publish","format-standard","hentry","category-prhae","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/189782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=189782"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/189782\/revisions"}],"predecessor-version":[{"id":227256,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/189782\/revisions\/227256"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=189782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=189782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=189782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}