{"id":27456,"date":"2020-01-15T05:37:00","date_gmt":"2020-01-15T08:37:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portal\/?post_type=portarias&#038;p=27456"},"modified":"2024-04-24T10:58:19","modified_gmt":"2024-04-24T13:58:19","slug":"rt-2020-00213","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/rt-2020-00213\/","title":{"rendered":"PORTARIA N\u00ba 00213\/REITORIA, DE 15 DE JANEIRO DE 2020"},"content":{"rendered":"\n<p><strong>O Reitor da Universidade Federal do Paran\u00e1, <\/strong>no uso de suas atribui\u00e7\u00f5es e tendo em vista o que consta no processo n\u00ba 23075.070779\/2018-90, <\/p>\n\n\n\n<p>RESOLVE:<\/p>\n\n\n\n<p>I. Revogar a Portaria n\u00ba 135\/REITORIA, de 14 de fevereiro de 2019.<\/p>\n\n\n\n<p>II. Conceder jornada flexibilizada, tendo  em vista o que consta na Portaria n\u00ba 643\/REITORIA, de 26 de novembro de  2018, retificada pela Portaria n\u00ba 692\/REITORIA, de 17 de dezembro de  2018, no per\u00edodo de 01 de janeiro de 2020 a 31 de dezembro de 2020, \u00e0  servidora GILIANE SANFELICE LEHMKUHL BATISTA &#8211; 1885606, ocupante do  cargo de Assistente em Administra\u00e7\u00e3o, enquanto estiver lotada na  Coordena\u00e7\u00e3o do Curso de Letras do Setor de Ci\u00eancias Humanas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I. Revogar a Portaria n\u00ba 135\/REITORIA, de 14 de fevereiro de 2019.  II. Conceder jornada flexibilizada, tendo em vista o que consta na Portaria n\u00ba 643\/REITORIA, de 26 de novembro de 2018, retificada pela Portaria n\u00ba 692\/REITORIA, de 17 de dezembro de 2018, no per\u00edodo de 01 de janeiro de 2020 a 31 de dezembro de 2020, \u00e0 servidora GILIANE SANFELICE LEHMKUHL BATISTA &#8211; 1885606, ocupante do cargo de Assistente em Administra\u00e7\u00e3o, enquanto estiver lotada na Coordena\u00e7\u00e3o do Curso de Letras do Setor de Ci\u00eancias Humanas.<\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":5,"footnotes":""},"categories":[117],"tags":[133],"class_list":["post-27456","post","type-post","status-publish","format-standard","hentry","category-rt","tag-jornada-flexibilizada"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/27456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=27456"}],"version-history":[{"count":2,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/27456\/revisions"}],"predecessor-version":[{"id":255560,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/27456\/revisions\/255560"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=27456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=27456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=27456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}