{"id":41658,"date":"2020-03-11T05:07:00","date_gmt":"2020-03-11T08:07:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portal\/?post_type=portarias&#038;p=41658"},"modified":"2023-08-03T13:18:51","modified_gmt":"2023-08-03T16:18:51","slug":"rt-2020-00676","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/rt-2020-00676\/","title":{"rendered":"PORTARIA N\u00ba 00676\/REITORIA, DE 11 DE MAR\u00c7O DE 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>O Reitor da Universidade Federal do Paran\u00e1, <\/strong>no uso de suas atribui\u00e7\u00f5es considerando o que consta no artigo 9\u00ba, inciso II da Lei n\u00ba 8.112\/90 e tendo em vista o que consta no processo n\u00ba 23075.017028\/2020-60, <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">RESOLVE: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alterar a Portaria n\u00ba 788\/REITORIA, de 20 de\nsetembro de 2019, publicada no Di\u00e1rio Oficial da Uni\u00e3o de&nbsp;23 de setembro\nde 2019, se\u00e7\u00e3o 2, p\u00e1g. 36, referente \u00e0 nomea\u00e7\u00e3o da servidora LORENA VON\nLINSINGEN&nbsp;&#8211; 1170173, na fun\u00e7\u00e3o de Assessora, FG-03, da Assessoria da\nCoordenadoria de Planejamento de Pessoal da Pr\u00f3-Reitoria de Gest\u00e3o de\nPessoas,&nbsp;para fazer constar que, a partir da data de publica\u00e7\u00e3o em DOU\ndesta Portaria, a referida fun\u00e7\u00e3o&nbsp; gratificada passa a denominar-se Chefe\nda Se\u00e7\u00e3o de Apoio Administrativo, FG-03, da Coordenadoria de Planejamento de\nPessoal da Pr\u00f3-Reitoria de Gest\u00e3o de Pessoas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:right\"><strong>RICARDO MARCELO FONSECA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Reitor da Universidade Federal do Paran\u00e1, no uso de suas atribui\u00e7\u00f5es considerando o que consta no artigo 9\u00ba, inciso II da Lei n\u00ba 8.112\/90 e tendo em vista o que consta no processo n\u00ba 23075.017028\/2020-60, RESOLVE: Alterar a Portaria n\u00ba 788\/REITORIA, de 20 de setembro de 2019, publicada no Di\u00e1rio Oficial da Uni\u00e3o de&nbsp;23&hellip; <a class=\"more-link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/rt-2020-00676\/\">Continue lendo <span class=\"screen-reader-text\">PORTARIA N\u00ba 00676\/REITORIA, DE 11 DE MAR\u00c7O DE 2020<\/span><\/a><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[117],"tags":[120],"class_list":["post-41658","post","type-post","status-publish","format-standard","hentry","category-rt","tag-funcao","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/41658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=41658"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/41658\/revisions"}],"predecessor-version":[{"id":193922,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/41658\/revisions\/193922"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=41658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=41658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=41658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}