{"id":47190,"date":"2020-06-22T10:00:00","date_gmt":"2020-06-22T13:00:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portal\/?post_type=portarias&#038;p=47190"},"modified":"2023-08-03T12:56:21","modified_gmt":"2023-08-03T15:56:21","slug":"progepe-2020-01843","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/progepe-2020-01843\/","title":{"rendered":"PORTARIA N\u00ba 01843\/PROGEPE, DE 22 DE JUNHO DE 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>O Pr\u00f3-Reitor de Gest\u00e3o de Pessoas da Universidade Federal do Paran\u00e1, <\/strong>no  uso de suas atribui\u00e7\u00f5es, tendo em vista a compet\u00eancia que lhe \u00e9  conferida pela Portaria n\u00ba 2.590, de 26 de setembro de 1997, de acordo  com os Artigos 11 e 12 da Lei n\u00ba 11.091\/05; os Anexos II e III do  Decreto n\u00ba 5.824\/06, Portaria n\u00ba 18.908\/2016 PROGEPE\/UFPR; Of\u00edcio  Circular SEI n\u00ba 2\/2019\/CGCARASSES\/CGCAR\/DESEN\/SGP\/SEDGG-ME; e, o que  consta no processo n\u00ba 23075.018907\/2020-17; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">RESOLVE:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Conceder o Incentivo \u00e0 Qualifica\u00e7\u00e3o no percentual 75% (setenta e cinco)  por cento, a partir de 12 de maio de 2020, ao servidor THOMPSON RICARDO  WEISER MEIER &#8211; 1021271, ocupante do cargo de T\u00e9cnico de Laborat\u00f3rio  \u00c1rea, lotado no Departamento de Engenharias e Exatas do Setor Palotina,  tendo em vista ter apresentado Declara\u00e7\u00e3o de Conclus\u00e3o do curso de  P\u00f3s-Gradua\u00e7\u00e3o em n\u00edvel de\u202fDoutorado\u202fem Engenharia Qu\u00edmica, emitido pela  Unioeste &#8211;\u00a0Universidade Estadual do Oeste do Paran\u00e1. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:right\"><strong>DOUGLAS ORTIZ HAMERMULLER<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conceder o Incentivo \u00e0 Qualifica\u00e7\u00e3o no percentual 75% (setenta e cinco) por cento, a partir de 12 de maio de 2020, ao servidor THOMPSON RICARDO WEISER MEIER &#8211; 1021271, ocupante do cargo de T\u00e9cnico de Laborat\u00f3rio \u00c1rea, lotado no Departamento de Engenharias e Exatas do Setor Palotina, tendo em vista ter apresentado Declara\u00e7\u00e3o de Conclus\u00e3o do curso de P\u00f3s-Gradua\u00e7\u00e3o em n\u00edvel de\u202fDoutorado\u202fem Engenharia Qu\u00edmica, emitido pela Unioeste &#8211;\u00a0Universidade Estadual do Oeste do Paran\u00e1.  <!-- wp:paragraph {\"align\":\"right\"} \n\n<p style=\"text-align:right\"><strong>DOUGLAS ORTIZ HAMERMULLER<\/strong>\n<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[116],"tags":[142],"class_list":["post-47190","post","type-post","status-publish","format-standard","hentry","category-progepe","tag-incentivo-qualificacao","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/47190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=47190"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/47190\/revisions"}],"predecessor-version":[{"id":194756,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/47190\/revisions\/194756"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=47190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=47190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=47190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}