{"id":63299,"date":"2020-12-15T05:01:00","date_gmt":"2020-12-15T08:01:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portal\/?post_type=portarias&#038;p=63299"},"modified":"2023-08-03T13:21:03","modified_gmt":"2023-08-03T16:21:03","slug":"rt-2020-01642","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/rt-2020-01642\/","title":{"rendered":"PORTARIA N\u00ba 01642\/REITORIA, DE 15 DE DEZEMBRO DE 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>O Reitor da Universidade Federal do Paran\u00e1, <\/strong>no uso de\nsuas atribui\u00e7\u00f5es e tendo em\nvista o que consta no processo n\u00ba 23075.066040\/2020-06,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">RESOLVE:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I. Designar\no servidor FRANCISCO DE ASSIS DO REGO MONTEIRO ROCHA JUNIOR &#8211; 1140633, Professor\ndo Magist\u00e9rio Superior, como representante do Setor de Ci\u00eancias Jur\u00eddicas,\njunto a Comiss\u00e3o Permanente de Pessoal Docente &#8211; CPPD, por 02 (dois) anos, a\npartir de 15 de dezembro de 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">II. Esta\nPortaria cessa, a partir de 15 de dezembro de 2020, os efeitos da Portaria n\u00ba\n486\/REITORIA, de 19 de junho de 2019. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:right\">Ricardo\nMarcelo Fonseca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I. Designar o servidor FRANCISCO DE ASSIS DO REGO MONTEIRO ROCHA JUNIOR &#8211; 1140633, Professor do Magist\u00e9rio Superior, como representante do Setor de Ci\u00eancias Jur\u00eddicas, junto a Comiss\u00e3o Permanente de Pessoal Docente &#8211; CPPD, por 02 (dois) anos, a partir de 15 de dezembro de 2020.  II. Esta Portaria cessa, a partir de 15 de dezembro de 2020, os efeitos da Portaria n\u00ba 486\/REITORIA, de 19 de junho de 2019.  <!-- wp:paragraph {\"align\":\"right\"} \n\n<p style=\"text-align:right\">Ricardo Marcelo Fonseca\n<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":1,"footnotes":""},"categories":[117],"tags":[126],"class_list":["post-63299","post","type-post","status-publish","format-standard","hentry","category-rt","tag-representante","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/63299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=63299"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/63299\/revisions"}],"predecessor-version":[{"id":196695,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/63299\/revisions\/196695"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=63299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=63299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=63299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}