{"id":64555,"date":"2020-12-07T05:03:00","date_gmt":"2020-12-07T08:03:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portal\/?post_type=portarias&#038;p=64555"},"modified":"2023-08-03T13:20:56","modified_gmt":"2023-08-03T16:20:56","slug":"rt-2020-01593","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/rt-2020-01593\/","title":{"rendered":"PORTARIA N\u00ba 01593\/REITORIA, DE 07 DE DEZEMBRO DE 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>O Reitor da Universidade Federal do Paran\u00e1, <\/strong>no uso de suas atribui\u00e7\u00f5es, tendo em vista o que consta no artigo 39 do Estatuto desta Universidade e o contido no processo n\u00ba 23075.059389\/2020-83, <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">RESOLVE: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I.&nbsp;Nomear a servidora PRISCILLA PLACHA S\u00c1 &#8211;\n1747605, ocupante do cargo de Professora, no regime de trabalho de 40\n(quarenta) horas semanais, para exercer a fun\u00e7\u00e3o de Suplente de&nbsp;Chefe do\nDepartamento de Direito Penal e Processual Penal do Setor de Ci\u00eancias\nJur\u00eddicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">II.&nbsp;O mandato ser\u00e1 de 02 (dois) anos, a partir\nda data de publica\u00e7\u00e3o em DOU da portaria de nomea\u00e7\u00e3o do(a) titular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">III.&nbsp;Nos impedimentos do(a) Chefe, a\nmencionada docente cumprir\u00e1, obrigatoriamente, o regime de trabalho de tempo\nintegral, de acordo com o disposto no \u00a7 5\u00ba, artigo 1\u00ba da Lei n\u00ba 8.168\/91.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>RICARDO\nMARCELO FONSECA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Reitor da Universidade Federal do Paran\u00e1, no uso de suas atribui\u00e7\u00f5es, tendo em vista o que consta no artigo 39 do Estatuto desta Universidade e o contido no processo n\u00ba 23075.059389\/2020-83, RESOLVE: I.&nbsp;Nomear a servidora PRISCILLA PLACHA S\u00c1 &#8211; 1747605, ocupante do cargo de Professora, no regime de trabalho de 40 (quarenta) horas semanais,&hellip; <a class=\"more-link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/rt-2020-01593\/\">Continue lendo <span class=\"screen-reader-text\">PORTARIA N\u00ba 01593\/REITORIA, DE 07 DE DEZEMBRO DE 2020<\/span><\/a><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":1,"footnotes":""},"categories":[117],"tags":[120],"class_list":["post-64555","post","type-post","status-publish","format-standard","hentry","category-rt","tag-funcao","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/64555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=64555"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/64555\/revisions"}],"predecessor-version":[{"id":196863,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/64555\/revisions\/196863"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=64555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=64555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=64555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}