{"id":70409,"date":"2019-04-15T05:02:00","date_gmt":"2019-04-15T08:02:00","guid":{"rendered":"http:\/\/progepe.ufpr.br\/portarias\/rt-2019-00339\/"},"modified":"2023-08-03T13:15:05","modified_gmt":"2023-08-03T16:15:05","slug":"rt-2019-00339","status":"publish","type":"post","link":"https:\/\/progepe.ufpr.br\/portarias\/rt-2019-00339\/","title":{"rendered":"PORTARIA N\u00ba 00339\/REITORIA, DE 15 DE ABRIL DE 2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Reitor da Universidade Federal do Paran\u00e1, no uso de suas atribui\u00e7\u00f5es, tendo em vista o que consta no artigo 50, \u00a7 1\u00ba do Estatuto desta Universidade e o que consta no processo n\u00ba 23075.013251\/2019-02,<\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>RESOLVE:<\/strong><\/p>\n\n\n<p class=\"wp-block-paragraph\">I. Nomear o servidor JUAREZ BERGMANN FILHO &#8211; 1715049, ocupante do cargo de Professor, no regime de trabalho de dedica\u00e7\u00e3o exclusiva, para exercer a fun\u00e7\u00e3o de Coordenador do Curso Superior de Tecnologia em Luteria do Setor de Educa\u00e7\u00e3o Profissional e Tecnol\u00f3gica, FCC \u2013 Fun\u00e7\u00e3o Comissionada de Coordena\u00e7\u00e3o de Curso, autorizada pela Lei n\u00ba 12.677, de 25 de junho de 2012, publicado no DOU de 26.06.2012 e Portaria\/MEC n\u00ba 1.172, de 17 de setembro de 2012, pelo per\u00edodo de 02 (dois) anos, a partir da data de publica\u00e7\u00e3o em DOU, de acordo com a Lei n\u00ba 9.527\/97.<\/p><p class=\"wp-block-paragraph\"> II. O mencionado docente cumprir\u00e1, obrigatoriamente, o regime de trabalho de tempo integral, de acordo com o disposto no \u00a7 5\u00ba, artigo 1\u00ba da Lei n\u00ba 8.168\/91.<\/p><p class=\"wp-block-paragraph\"><\/p>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-b1849663 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-outline has-small-font-size is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"https:\/\/progepe.ufpr.br\/portarias\/wp-content\/uploads\/sites\/3\/pcp\/RT\/2019\/339R.pdf\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse o arquivo da portaria<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I. Nomear o servidor JUAREZ BERGMANN FILHO &#8211; 1715049, ocupante do cargo de Professor, no regime de trabalho de dedica\u00e7\u00e3o exclusiva, para exercer a fun\u00e7\u00e3o de Coordenador do Curso Superior de Tecnologia em Luteria do Setor de Educa\u00e7\u00e3o Profissional e Tecnol\u00f3gica, FCC \u2013 Fun\u00e7\u00e3o Comissionada de Coordena\u00e7\u00e3o de Curso, autorizada pela Lei n\u00ba 12.677, de 25 de junho de 2012, publicado no DOU de 26.06.2012 e Portaria\/MEC n\u00ba 1.172, de 17 de setembro de 2012, pelo per\u00edodo de 02 (dois) anos, a partir da data de publica\u00e7\u00e3o em DOU, de acordo com a Lei n\u00ba 9.527\/97. II. O<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[117],"tags":[243],"class_list":["post-70409","post","type-post","status-publish","format-standard","hentry","category-rt","tag-coordenador-vice","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/70409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/comments?post=70409"}],"version-history":[{"count":1,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/70409\/revisions"}],"predecessor-version":[{"id":125758,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/posts\/70409\/revisions\/125758"}],"wp:attachment":[{"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/media?parent=70409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/categories?post=70409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progepe.ufpr.br\/portarias\/wp-json\/wp\/v2\/tags?post=70409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}